{"id":25,"count":4,"description":"I nostri crackers sono fatti con 100% di olio extra vergine di oliva e soltanto con ingredienti di origine vegetale. Proponiamo 4 ricette caratterizzate da ingredienti italiani: classici al sale di Cervia, al rosmarino, al peperoncino, con pomodoro e basilico. I crackers della DESEO sono sottili e croccanti, da gustare a piacimento in qualsiasi momento della giornata; ottimi come snack o perfetta base per creare  i tuoi stuzzichini preferiti.","link":"https:\/\/www.biscottideseo.it\/en\/product-category\/crackers-allolio-evo\/","name":"Crackers all'olio evo","slug":"crackers-allolio-evo","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.biscottideseo.it\/en\/wp-json\/wp\/v2\/product_cat\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biscottideseo.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.biscottideseo.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.biscottideseo.it\/en\/wp-json\/wp\/v2\/product?product_cat=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}